{"id":1519,"date":"2021-12-22T12:48:57","date_gmt":"2021-12-22T10:48:57","guid":{"rendered":"https:\/\/www.birsesti.ro\/wordpress\/?page_id=1519"},"modified":"2022-12-22T12:50:31","modified_gmt":"2022-12-22T10:50:31","slug":"proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4","status":"publish","type":"page","link":"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/","title":{"rendered":"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d &#8211; Nr. ref. 2020-1-BE01-KA229-074917_4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":1000,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1519","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d - Nr. ref. 2020-1-BE01-KA229-074917_4 - Liceul Tehnologic B\u00e2rse\u0219ti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d - Nr. ref. 2020-1-BE01-KA229-074917_4 - Liceul Tehnologic B\u00e2rse\u0219ti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/\" \/>\n<meta property=\"og:site_name\" content=\"Liceul Tehnologic B\u00e2rse\u0219ti\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-22T10:50:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/proiecte-2__trashed\\\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\\\/\",\"url\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/proiecte-2__trashed\\\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\\\/\",\"name\":\"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d - Nr. ref. 2020-1-BE01-KA229-074917_4 - Liceul Tehnologic B\u00e2rse\u0219ti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/#website\"},\"datePublished\":\"2021-12-22T10:48:57+00:00\",\"dateModified\":\"2022-12-22T10:50:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/proiecte-2__trashed\\\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/proiecte-2__trashed\\\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/proiecte-2__trashed\\\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proiecte\",\"item\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/?page_id=1000\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d &#8211; Nr. ref. 2020-1-BE01-KA229-074917_4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/\",\"name\":\"Liceul Tehnologic B\u00e2rse\u0219ti\",\"description\":\"Agricultura este motorul economiei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d - Nr. ref. 2020-1-BE01-KA229-074917_4 - Liceul Tehnologic B\u00e2rse\u0219ti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/","og_locale":"ro_RO","og_type":"article","og_title":"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d - Nr. ref. 2020-1-BE01-KA229-074917_4 - Liceul Tehnologic B\u00e2rse\u0219ti","og_url":"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/","og_site_name":"Liceul Tehnologic B\u00e2rse\u0219ti","article_modified_time":"2022-12-22T10:50:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/","url":"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/","name":"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d - Nr. ref. 2020-1-BE01-KA229-074917_4 - Liceul Tehnologic B\u00e2rse\u0219ti","isPartOf":{"@id":"https:\/\/www.birsesti.ro\/wordpress\/#website"},"datePublished":"2021-12-22T10:48:57+00:00","dateModified":"2022-12-22T10:50:31+00:00","breadcrumb":{"@id":"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.birsesti.ro\/wordpress\/proiecte-2__trashed\/proiect-erasmus-partage-et-respect-de-nos-cultures-culinaires-et-traditionnelles-nr-ref-2020-1-be01-ka229-074917_4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/www.birsesti.ro\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Proiecte","item":"https:\/\/www.birsesti.ro\/wordpress\/?page_id=1000"},{"@type":"ListItem","position":3,"name":"Proiect ERASMUS+ \u201dPartage et respect de nos cultures culinaires et traditionnelles\u201d &#8211; Nr. ref. 2020-1-BE01-KA229-074917_4"}]},{"@type":"WebSite","@id":"https:\/\/www.birsesti.ro\/wordpress\/#website","url":"https:\/\/www.birsesti.ro\/wordpress\/","name":"Liceul Tehnologic B\u00e2rse\u0219ti","description":"Agricultura este motorul economiei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.birsesti.ro\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/pages\/1519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/comments?post=1519"}],"version-history":[{"count":0,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/pages\/1519\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/pages\/1000"}],"wp:attachment":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/media?parent=1519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}