{"id":1481,"date":"2022-10-14T09:18:55","date_gmt":"2022-10-14T06:18:55","guid":{"rendered":"https:\/\/www.birsesti.ro\/wordpress\/?p=1481"},"modified":"2022-10-14T09:19:01","modified_gmt":"2022-10-14T06:19:01","slug":"pas-2022-2026","status":"publish","type":"post","link":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/","title":{"rendered":"PAS 2022-2026"},"content":{"rendered":"<p><a href=\"https:\/\/www.birsesti.ro\/wordpress\/?attachment_id=1482\" rel=\"attachment wp-att-1482\">PAS LT Barsesti anul 2022-2026<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAS LT Barsesti anul 2022-2026<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1481","post","type-post","status-publish","format-standard","hentry","category-anunturi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PAS 2022-2026 - Liceul Tehnologic B\u00e2rse\u0219ti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAS 2022-2026 - Liceul Tehnologic B\u00e2rse\u0219ti\" \/>\n<meta property=\"og:description\" content=\"PAS LT Barsesti anul 2022-2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Liceul Tehnologic B\u00e2rse\u0219ti\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-14T06:18:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-14T06:19:01+00:00\" \/>\n<meta name=\"author\" content=\"Administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrator\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/\"},\"author\":{\"name\":\"Administrator\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/#\\\/schema\\\/person\\\/3f8a34fe3ddfbe67666039a61ba5195a\"},\"headline\":\"PAS 2022-2026\",\"datePublished\":\"2022-10-14T06:18:55+00:00\",\"dateModified\":\"2022-10-14T06:19:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/\"},\"wordCount\":7,\"commentCount\":0,\"articleSection\":[\"Anun\u021buri\"],\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/\",\"url\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/\",\"name\":\"PAS 2022-2026 - Liceul Tehnologic B\u00e2rse\u0219ti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/#website\"},\"datePublished\":\"2022-10-14T06:18:55+00:00\",\"dateModified\":\"2022-10-14T06:19:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/#\\\/schema\\\/person\\\/3f8a34fe3ddfbe67666039a61ba5195a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/pas-2022-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAS 2022-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/\",\"name\":\"Liceul Tehnologic B\u00e2rse\u0219ti\",\"description\":\"Agricultura este motorul economiei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/#\\\/schema\\\/person\\\/3f8a34fe3ddfbe67666039a61ba5195a\",\"name\":\"Administrator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d210dd77403da411a00c1ec760faf1357cf8fdfd7b964130f613e10063e51975?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d210dd77403da411a00c1ec760faf1357cf8fdfd7b964130f613e10063e51975?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d210dd77403da411a00c1ec760faf1357cf8fdfd7b964130f613e10063e51975?s=96&d=mm&r=g\",\"caption\":\"Administrator\"},\"url\":\"https:\\\/\\\/www.birsesti.ro\\\/wordpress\\\/author\\\/denisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAS 2022-2026 - Liceul Tehnologic B\u00e2rse\u0219ti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/","og_locale":"ro_RO","og_type":"article","og_title":"PAS 2022-2026 - Liceul Tehnologic B\u00e2rse\u0219ti","og_description":"PAS LT Barsesti anul 2022-2026","og_url":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/","og_site_name":"Liceul Tehnologic B\u00e2rse\u0219ti","article_published_time":"2022-10-14T06:18:55+00:00","article_modified_time":"2022-10-14T06:19:01+00:00","author":"Administrator","twitter_card":"summary_large_image","twitter_misc":{"Scris de":"Administrator"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/#article","isPartOf":{"@id":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/"},"author":{"name":"Administrator","@id":"https:\/\/www.birsesti.ro\/wordpress\/#\/schema\/person\/3f8a34fe3ddfbe67666039a61ba5195a"},"headline":"PAS 2022-2026","datePublished":"2022-10-14T06:18:55+00:00","dateModified":"2022-10-14T06:19:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/"},"wordCount":7,"commentCount":0,"articleSection":["Anun\u021buri"],"inLanguage":"ro-RO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/","url":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/","name":"PAS 2022-2026 - Liceul Tehnologic B\u00e2rse\u0219ti","isPartOf":{"@id":"https:\/\/www.birsesti.ro\/wordpress\/#website"},"datePublished":"2022-10-14T06:18:55+00:00","dateModified":"2022-10-14T06:19:01+00:00","author":{"@id":"https:\/\/www.birsesti.ro\/wordpress\/#\/schema\/person\/3f8a34fe3ddfbe67666039a61ba5195a"},"breadcrumb":{"@id":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.birsesti.ro\/wordpress\/pas-2022-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/www.birsesti.ro\/wordpress\/"},{"@type":"ListItem","position":2,"name":"PAS 2022-2026"}]},{"@type":"WebSite","@id":"https:\/\/www.birsesti.ro\/wordpress\/#website","url":"https:\/\/www.birsesti.ro\/wordpress\/","name":"Liceul Tehnologic B\u00e2rse\u0219ti","description":"Agricultura este motorul economiei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.birsesti.ro\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Person","@id":"https:\/\/www.birsesti.ro\/wordpress\/#\/schema\/person\/3f8a34fe3ddfbe67666039a61ba5195a","name":"Administrator","image":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/secure.gravatar.com\/avatar\/d210dd77403da411a00c1ec760faf1357cf8fdfd7b964130f613e10063e51975?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d210dd77403da411a00c1ec760faf1357cf8fdfd7b964130f613e10063e51975?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d210dd77403da411a00c1ec760faf1357cf8fdfd7b964130f613e10063e51975?s=96&d=mm&r=g","caption":"Administrator"},"url":"https:\/\/www.birsesti.ro\/wordpress\/author\/denisa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/posts\/1481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/comments?post=1481"}],"version-history":[{"count":0,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/posts\/1481\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/media?parent=1481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/categories?post=1481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.birsesti.ro\/wordpress\/wp-json\/wp\/v2\/tags?post=1481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}